{"id":2397,"date":"2021-04-27T22:16:39","date_gmt":"2021-04-27T22:16:39","guid":{"rendered":"http:\/\/arco.iamabdus.com\/v1.0\/?page_id=2397"},"modified":"2023-03-22T23:57:41","modified_gmt":"2023-03-22T23:57:41","slug":"servicios","status":"publish","type":"page","link":"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/","title":{"rendered":"Servicios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2397\" class=\"elementor elementor-2397\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f35f668 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f35f668\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-275d1113\" data-id=\"275d1113\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b22f51b elementor-widget elementor-widget-heading\" data-id=\"b22f51b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Dise\u00f1o de cocinas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380613f elementor-widget elementor-widget-text-editor\" data-id=\"380613f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Pioneros en el \u00e1rea de dise\u00f1o de cocinas , 19 a\u00f1os de experiencia respaldan la calidad de servicio y material de nuestros proyectos; ofrecemos un servicio personalizado y de alta calidad; brindamos asesor\u00eda para mejor distribuci\u00f3n y funcionalidad de tu cocina.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-813e88f elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"813e88f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/wa.me\/526121632718\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita tu proyecto<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e095ab\" data-id=\"1e095ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4396825c elementor-widget elementor-widget-image\" data-id=\"4396825c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/c29-1024x576.jpg\" class=\"attachment-large size-large wp-image-6144\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/c29-1024x576.jpg 1024w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/c29-300x169.jpg 300w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/c29-768x432.jpg 768w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/c29.jpg 1056w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-768da15f elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"768da15f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3849e302\" data-id=\"3849e302\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73453a16 elementor-widget elementor-widget-image\" data-id=\"73453a16\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"600\" src=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/m3-1024x600.png\" class=\"attachment-large size-large wp-image-6157\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/m3-1024x600.png 1024w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/m3-300x176.png 300w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/m3-768x450.png 768w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/m3-1536x899.png 1536w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/m3-2048x1199.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2140d394\" data-id=\"2140d394\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b526899 elementor-widget elementor-widget-heading\" data-id=\"4b526899\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dise\u00f1o de mobiliario<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f0d772 elementor-widget elementor-widget-text-editor\" data-id=\"57f0d772\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Dise\u00f1amos mobiliario de manera personalizada, adaptando su estilo, concepto y esencia, cubriendo las necesidades del espacio y la funcionalidad del mobiliario para lograr espacios con armon\u00eda y dise\u00f1o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e764e94 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e764e94\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/wa.me\/526121632718\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita tu proyecto<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1277223e elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1277223e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6700b42e\" data-id=\"6700b42e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e2c6461 elementor-widget elementor-widget-heading\" data-id=\"4e2c6461\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dise\u00f1o de interiores<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-343bd002 elementor-widget elementor-widget-text-editor\" data-id=\"343bd002\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Trabajamos proyectos de dise\u00f1o de interiores residencial con una atenci\u00f3n personalizada, para llevar las ideas y sue\u00f1os a una realidad creativa, donde se obtendr\u00e1 un espacio visualizado en un proyecto con im\u00e1genes en 3D , solucionando las necesidades del cliente y facilitando la toma de decisiones referentes a su espacio.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a945455 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a945455\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/wa.me\/526121632718\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita tu proyecto<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d04656f\" data-id=\"4d04656f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6aded93c elementor-widget elementor-widget-image\" data-id=\"6aded93c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/p16-1024x576.png\" class=\"attachment-large size-large wp-image-6128\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/p16-1024x576.png 1024w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/p16-300x169.png 300w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/p16-768x432.png 768w, https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/08\/p16.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf1a6b0 elementor-section-content-middle elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf1a6b0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-455fa1e3\" data-id=\"455fa1e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18f2b4a3 elementor-widget elementor-widget-heading\" data-id=\"18f2b4a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 incluyen nuestros proyectos?<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b1f2763 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b1f2763\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7939bd0\" data-id=\"7939bd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6df6728 elementor-widget elementor-widget-heading\" data-id=\"6df6728\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Render<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dad490 elementor-widget elementor-widget-text-editor\" data-id=\"8dad490\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Se presenta al cliente una visualizaci\u00f3n del proyecto por medio de un render donde podr\u00e1 tener una idea proyectada de su proyecto.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ebe21ba\" data-id=\"ebe21ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725c8d0 elementor-widget elementor-widget-heading\" data-id=\"725c8d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Cotizaci\u00f3n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b84dcf4 elementor-widget elementor-widget-text-editor\" data-id=\"b84dcf4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Brindamos una cotizaci\u00f3n enfocada en cada proyecto considerando funcionalidad, materiales y su prespuesto a invertir deseado para asesorar y lograr un\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7e2c908\" data-id=\"7e2c908\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5262fa elementor-widget elementor-widget-heading\" data-id=\"f5262fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Muebles y accesorios<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2037b35 elementor-widget elementor-widget-text-editor\" data-id=\"2037b35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Dentro del proyecto se pueden incluir muebles y accesorios que podemos encontrar con la amplia variedad de proveedores en Tu. Decoraci\u00f3n. para brindar m\u00e1s estilo y dise\u00f1o a tu proyecto.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed56606 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed56606\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30e8401\" data-id=\"30e8401\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e7cc66 elementor-widget elementor-widget-heading\" data-id=\"5e7cc66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nuestros beneficios<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11a92f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11a92f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8705f8e\" data-id=\"8705f8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06854ca elementor-align-center elementor-widget elementor-widget-bdt-dropbar\" data-id=\"06854ca\" data-element_type=\"widget\" data-widget_type=\"bdt-dropbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-dropbar-wrapper\">\n\t\t\t<a class=\"bdt-dropbar-button elementor-button elementor-size-sm\" href=\"javascript:void(0)\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t<span >\n\n\t\t\t\t<span class=\"elementor-button-text\">Servicio personalizado<\/span>\n\n\t\t\t\t\n\t\t\t<\/span>\n\t\t<\/span>\n\t\t\t<\/a>\n\t\t\t<div id=\"bdt-drop-06854ca\" class=\"bdt-drop\" data-bdt-drop=\"{&quot;pos&quot;:&quot;bottom-justify&quot;,&quot;mode&quot;:&quot;hover&quot;,&quot;delay-show&quot;:0,&quot;delay-hide&quot;:800,&quot;flip&quot;:false,&quot;offset&quot;:5,&quot;animation&quot;:&quot;bdt-animation-fade&quot;,&quot;duration&quot;:200}\">\n\t\t\t\t<div class=\"bdt-card bdt-card-body bdt-card-default bdt-text-left\">\n\t\t\t\t\t<p style=\"text-align: center\">Para el dise\u00f1o de su cocina, recibir\u00e1 un servicio personalizado donde le recibiremos en una cita para conocer cada detalle a lograr en su cocina. Le acompa\u00f1aremos en cada etapa de su cocina.<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-335e64b\" data-id=\"335e64b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1954ae elementor-align-center elementor-widget elementor-widget-bdt-dropbar\" data-id=\"e1954ae\" data-element_type=\"widget\" data-widget_type=\"bdt-dropbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-dropbar-wrapper\">\n\t\t\t<a class=\"bdt-dropbar-button elementor-button elementor-size-sm\" href=\"javascript:void(0)\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t<span >\n\n\t\t\t\t<span class=\"elementor-button-text\">Dise\u00f1o \u00fanico<\/span>\n\n\t\t\t\t\n\t\t\t<\/span>\n\t\t<\/span>\n\t\t\t<\/a>\n\t\t\t<div id=\"bdt-drop-e1954ae\" class=\"bdt-drop\" data-bdt-drop=\"{&quot;pos&quot;:&quot;bottom-left&quot;,&quot;mode&quot;:&quot;hover&quot;,&quot;delay-show&quot;:0,&quot;delay-hide&quot;:800,&quot;flip&quot;:false,&quot;offset&quot;:10,&quot;animation&quot;:&quot;bdt-animation-fade&quot;,&quot;duration&quot;:200}\">\n\t\t\t\t<div class=\"bdt-card bdt-card-body bdt-card-default bdt-text-left\">\n\t\t\t\t\t<p style=\"text-align: center\">Su dise\u00f1o es \u00fanico y personalizado, teniendo las medidas del espacio e informaci\u00f3n de c\u00f3mo vive el d\u00eda a d\u00eda, cu\u00e1ntas personas disfrutan de su cocina, estilos y colores de inspiraci\u00f3n, entre otra informaci\u00f3n adquirida durante su entrevista. Evaluamos la mejor opci\u00f3n de dise\u00f1o para que disfrute al 100% de su cocina.<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-dd5aa5a\" data-id=\"dd5aa5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf4f52e elementor-align-center elementor-widget elementor-widget-bdt-dropbar\" data-id=\"bf4f52e\" data-element_type=\"widget\" data-widget_type=\"bdt-dropbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-dropbar-wrapper\">\n\t\t\t<a class=\"bdt-dropbar-button elementor-button elementor-size-sm\" href=\"javascript:void(0)\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t<span >\n\n\t\t\t\t<span class=\"elementor-button-text\">Variedad de productos<\/span>\n\n\t\t\t\t\n\t\t\t<\/span>\n\t\t<\/span>\n\t\t\t<\/a>\n\t\t\t<div id=\"bdt-drop-bf4f52e\" class=\"bdt-drop\" data-bdt-drop=\"{&quot;pos&quot;:&quot;bottom-left&quot;,&quot;mode&quot;:&quot;hover&quot;,&quot;delay-show&quot;:0,&quot;delay-hide&quot;:800,&quot;flip&quot;:false,&quot;offset&quot;:10,&quot;animation&quot;:&quot;bdt-animation-fade&quot;,&quot;duration&quot;:200}\">\n\t\t\t\t<div class=\"bdt-card bdt-card-body bdt-card-default bdt-text-left\">\n\t\t\t\t\t<p style=\"text-align: center\">Contamos con una amplia gama de muebles y accesorios de la mejor calidad, as\u00ed como electrodomesticos y otros materiales; seleccionamos la mejor opci\u00f3n para su proyecto con el objetivo de brindar un proyecto integral y completo.<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-75ed17c\" data-id=\"75ed17c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a8f538 elementor-align-center elementor-widget elementor-widget-bdt-dropbar\" data-id=\"9a8f538\" data-element_type=\"widget\" data-widget_type=\"bdt-dropbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-dropbar-wrapper\">\n\t\t\t<a class=\"bdt-dropbar-button elementor-button elementor-size-sm\" href=\"javascript:void(0)\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t<span >\n\n\t\t\t\t<span class=\"elementor-button-text\">Optimizamos presupuesto<\/span>\n\n\t\t\t\t\n\t\t\t<\/span>\n\t\t<\/span>\n\t\t\t<\/a>\n\t\t\t<div id=\"bdt-drop-9a8f538\" class=\"bdt-drop\" data-bdt-drop=\"{&quot;pos&quot;:&quot;bottom-left&quot;,&quot;mode&quot;:&quot;hover&quot;,&quot;delay-show&quot;:0,&quot;delay-hide&quot;:800,&quot;flip&quot;:false,&quot;offset&quot;:10,&quot;animation&quot;:&quot;bdt-animation-fade&quot;,&quot;duration&quot;:200}\">\n\t\t\t\t<div class=\"bdt-card bdt-card-body bdt-card-default bdt-text-left\">\n\t\t\t\t\t<p style=\"text-align: center\">Cada cocina es personalizada, una vez establecido cu\u00e1nto quiere invertir en su proyecto. Nuestro dise\u00f1o, materiales, y funcionamientos en cocina, ser\u00e1n adaptados para optimizar su presupuesto y lograr resultados \u00fanicos e incre\u00edbles.<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-820f375 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"820f375\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/wa.me\/526121632718\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita tu proyecto<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3496982 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3496982\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13828f7\" data-id=\"13828f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ba3976 elementor-button-align-start elementor-widget elementor-widget-bdt-contact-form\" data-id=\"1ba3976\" data-element_type=\"widget\" data-widget_type=\"bdt-contact-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-contact-form bdt-contact-form-skin-default\">\n\t\t\t<div class=\"elementor-form-fields-wrapper\">\n\t\t\t\t\t\t<div class=\"bdt-contact-form-wrapper\">\n\t\t\t<form class=\"bdt-contact-form-form bdt-form-stacked bdt-grid bdt-grid-small without-recaptcha\" data-bdt-grid=\"\" action=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-admin\/admin-ajax.php\" method=\"post\">\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-field-group elementor-field-required bdt-width-1-1\">\n\t\t\t\t\t\t<label for=\"user_name1ba3976\" class=\"bdt-form-label\">Nombre<\/label><div class=\"bdt-form-controls\"><input type=\"text\" name=\"name\" id=\"user_name1ba3976\" placeholder=\"Name\" class=\"bdt-input bdt-form-small\" required =\"required\"><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"bdt-field-group elementor-field-required bdt-width-1-1\">\n\t\t\t\t\t\t<label for=\"email1ba3976\" class=\"bdt-form-label\">Email<\/label><div class=\"bdt-form-controls\"><input type=\"email\" name=\"email\" id=\"email1ba3976\" placeholder=\"example@email.com\" class=\"bdt-input bdt-form-small\" required=\"required\"><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-field-group bdt-width-1-1 elementor-field-required\">\n\t\t\t\t\t\t\t<label for=\"contact1ba3976\" class=\"bdt-form-label\">N\u00famero celular <\/label><div class=\"bdt-form-controls\"><input type=\"tel\" name=\"contact\" id=\"contact1ba3976\" placeholder=\"Phone number\" class=\"bdt-input bdt-form-small\"><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-field-group bdt-width-1-1 elementor-field-required\">\n\t\t\t\t\t\t\t<label for=\"subject1ba3976\" class=\"bdt-form-label\">Asunto<\/label><div class=\"bdt-form-controls\"><input type=\"text\" name=\"subject\" id=\"subject1ba3976\" placeholder=\"Subject\" class=\"bdt-input bdt-form-small\" required=\"required\"><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-field-group bdt-width-1-1 elementor-field-required\">\n\t\t\t\t\t\t\t<label for=\"message1ba3976\" class=\"bdt-form-label\">Mensaje<\/label><div class=\"bdt-form-controls\"><textarea name=\"message\" id=\"message1ba3976\" rows=\"5\" placeholder=\"Your Message Here\" class=\"bdt-textarea bdt-form-small\" required=\"required\"><\/textarea><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<input type=\"hidden\" class=\"widget_id\" name=\"widget_id\" value=\"1ba3976\"\/>\n\t\t\t\t\t<input type=\"hidden\" name=\"bdt-sf-1ba3976\" value=\"true\"\/>\n\t\t\t\t\t<input type=\"hidden\" class=\"page_id\" name=\"page_id\" value=\"2397\"\/>\n\n\t\t\t\t\t<div class=\"elementor-field-type-submit bdt-field-group bdt-flex bdt-width-1-1\">\n\t\t\t\t\t\t<button type=\"submit\" class=\"bdt-button-small elementor-animation-shrink elementor-button bdt-button bdt-button-primary\" name=\"submit\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Solicitar m\u00e1s informaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<input type=\"hidden\" name=\"action\" value=\"element_pack_contact_form\" \/>\n\n\t\t\t\t\t\n\t\t\t<\/form>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1o de cocinas Pioneros en el \u00e1rea de dise\u00f1o de cocinas , 19 a\u00f1os de experiencia respaldan la calidad de servicio y material de nuestros proyectos; ofrecemos un servicio personalizado y de alta calidad; brindamos asesor\u00eda para mejor distribuci\u00f3n y funcionalidad de tu cocina. Solicita tu proyecto Dise\u00f1o de mobiliario Dise\u00f1amos mobiliario de manera personalizada, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/\"> <span class=\"screen-reader-text\">Servicios<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5719,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Servicios -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios -\" \/>\n<meta property=\"og:description\" content=\"Dise\u00f1o de cocinas Pioneros en el \u00e1rea de dise\u00f1o de cocinas , 19 a\u00f1os de experiencia respaldan la calidad de servicio y material de nuestros proyectos; ofrecemos un servicio personalizado y de alta calidad; brindamos asesor\u00eda para mejor distribuci\u00f3n y funcionalidad de tu cocina. Solicita tu proyecto Dise\u00f1o de mobiliario Dise\u00f1amos mobiliario de manera personalizada, &hellip; Servicios Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tu.disenodecoracion\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T23:57:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/05\/background-servicios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1601\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/\",\"url\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/\",\"name\":\"Servicios -\",\"isPartOf\":{\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/#website\"},\"datePublished\":\"2021-04-27T22:16:39+00:00\",\"dateModified\":\"2023-03-22T23:57:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/#website\",\"url\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/\",\"name\":\"\",\"description\":\"#MuyT\u00fa\",\"publisher\":{\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/#organization\",\"name\":\"Tu Dise\u00f1o\",\"url\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/05\/Logo_TU._-Disenocolor.png\",\"contentUrl\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/05\/Logo_TU._-Disenocolor.png\",\"width\":1345,\"height\":1887,\"caption\":\"Tu Dise\u00f1o\"},\"image\":{\"@id\":\"https:\/\/tudisenodecoracion.com\/tudiseno\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Tu.disenodecoracion\",\"https:\/\/www.instagram.com\/tu.disenodecoracion\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/","og_locale":"es_MX","og_type":"article","og_title":"Servicios -","og_description":"Dise\u00f1o de cocinas Pioneros en el \u00e1rea de dise\u00f1o de cocinas , 19 a\u00f1os de experiencia respaldan la calidad de servicio y material de nuestros proyectos; ofrecemos un servicio personalizado y de alta calidad; brindamos asesor\u00eda para mejor distribuci\u00f3n y funcionalidad de tu cocina. Solicita tu proyecto Dise\u00f1o de mobiliario Dise\u00f1amos mobiliario de manera personalizada, &hellip; Servicios Leer m\u00e1s &raquo;","og_url":"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/","article_publisher":"https:\/\/www.facebook.com\/Tu.disenodecoracion","article_modified_time":"2023-03-22T23:57:41+00:00","og_image":[{"width":1601,"height":403,"url":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/05\/background-servicios.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/","url":"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/","name":"Servicios -","isPartOf":{"@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/#website"},"datePublished":"2021-04-27T22:16:39+00:00","dateModified":"2023-03-22T23:57:41+00:00","breadcrumb":{"@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/servicios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/tudisenodecoracion.com\/tudiseno\/"},{"@type":"ListItem","position":2,"name":"Servicios"}]},{"@type":"WebSite","@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/#website","url":"https:\/\/tudisenodecoracion.com\/tudiseno\/","name":"","description":"#MuyT\u00fa","publisher":{"@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tudisenodecoracion.com\/tudiseno\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/#organization","name":"Tu Dise\u00f1o","url":"https:\/\/tudisenodecoracion.com\/tudiseno\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/#\/schema\/logo\/image\/","url":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/05\/Logo_TU._-Disenocolor.png","contentUrl":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-content\/uploads\/2022\/05\/Logo_TU._-Disenocolor.png","width":1345,"height":1887,"caption":"Tu Dise\u00f1o"},"image":{"@id":"https:\/\/tudisenodecoracion.com\/tudiseno\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tu.disenodecoracion","https:\/\/www.instagram.com\/tu.disenodecoracion"]}]}},"_links":{"self":[{"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/pages\/2397"}],"collection":[{"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/comments?post=2397"}],"version-history":[{"count":86,"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/pages\/2397\/revisions"}],"predecessor-version":[{"id":6290,"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/pages\/2397\/revisions\/6290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/media\/5719"}],"wp:attachment":[{"href":"https:\/\/tudisenodecoracion.com\/tudiseno\/wp-json\/wp\/v2\/media?parent=2397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}